{"id":31,"date":"2023-06-10T21:30:10","date_gmt":"2023-06-10T14:30:10","guid":{"rendered":"http:\/\/media.ninhbinhweb.top\/?page_id=31"},"modified":"2026-01-21T23:03:57","modified_gmt":"2026-01-21T16:03:57","slug":"lien-he","status":"publish","type":"page","link":"https:\/\/amtmusic.vn\/vi\/lien-he\/","title":{"rendered":"Li\u00ean h\u1ec7"},"content":{"rendered":"\n  <div class=\"banner has-hover banner-dong-gop\" id=\"banner-423658307\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1797099831\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1><span style=\"font-size: 180%;\">Li\u00ean h\u1ec7 <strong>AMT MEDIA<\/strong><\/span><\/h1>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1797099831 {\n  width: 60%;\n}\n#text-box-1797099831 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-423658307 {\n  padding-top: 600px;\n}\n#banner-423658307 .bg.bg-loaded {\n  background-image: url(https:\/\/amtmusic.vn\/wp-content\/uploads\/2023\/06\/img-managed-right.jpg);\n}\n#banner-423658307 .overlay {\n  background-color: rgba(0, 0, 0, 0.297);\n}\n#banner-423658307 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-423658307 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\t<section class=\"section lien-he-1 dark\" id=\"section_1942143729\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-450863276\">\n\n\t<div id=\"col-1049221529\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3><span style=\"font-size: 100%;\">C\u00d4NG TY TNHH S\u00c1NG T\u1ea0O TRUY\u1ec0N TH\u00d4NG AMT MEDIA<\/span><\/h3>\n<ul>\n<li><span style=\"color: #999999;\">\u0110\u1ecba ch\u1ec9: C\u00f4ng ty TNHH S\u00e1ng T\u1ea1o Truy\u1ec1n Th\u00f4ng AMT MEDIA<\/span><\/li>\n<li><span style=\"color: #999999;\">\u0110i\u1ec7n tho\u1ea1i: 0388.129.843<\/span><\/li>\n<li><span style=\"color: #999999;\">Email: truyenthongamt@gmail.com<\/span><\/li>\n<li><span style=\"color: #999999;\">Website: www.amtmusic.vn<\/span><\/li>\n<\/ul>\n<div class=\"social-icons follow-icons full-width text-left\" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\" rel=\"noopener noreferrer nofollow\" class=\"icon plain facebook tooltip\" title=\"Follow on Facebook\" aria-label=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"TikTok\" class=\"icon plain tiktok tooltip\" title=\"Follow on TikTok\" aria-label=\"Follow on TikTok\"><i class=\"icon-tiktok\" ><\/i><\/a><a href=\"mailto:#\" data-label=\"E-mail\" rel=\"nofollow\" class=\"icon plain  email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:#\" target=\"_blank\" data-label=\"Phone\" rel=\"noopener noreferrer nofollow\" class=\"icon plain  phone tooltip\" title=\"Call us\" aria-label=\"Call us\"><i class=\"icon-phone\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"YouTube\" class=\"icon plain  youtube tooltip\" title=\"Follow on YouTube\" aria-label=\"Follow on YouTube\"><i class=\"icon-youtube\" ><\/i><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1049221529 > .col-inner {\n  padding: 0px 100px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1198987314\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f664-o1\" lang=\"vi\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/vi\/wp-json\/wp\/v2\/pages\/31\/#wpcf7-f664-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"664\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.8.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"vi\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f664-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"form-lien-he\">\n\t<h3>Contact us now!\n\t<\/h3>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-692\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your name\" value=\"\" type=\"text\" name=\"text-692\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-324\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number\" value=\"\" type=\"tel\" name=\"tel-324\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-820\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-text wpcf7-validates-as-email\" aria-invalid=\"false\" placeholder=\"Email address\" value=\"\" type=\"email\" name=\"email-820\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-3\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Content\" name=\"textarea-3\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner nut-gioi-thieu\" type=\"submit\" value=\"Sent information\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1198987314 > .col-inner {\n  padding: 50px 50px 50px 50px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1942143729 {\n  padding-top: 80px;\n  padding-bottom: 80px;\n  background-color: rgb(27, 27, 27);\n}\n#section_1942143729 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1942143729 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"footnotes":""},"class_list":["post-31","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/pages\/31\/"}],"collection":[{"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/comments\/?post=31"}],"version-history":[{"count":12,"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/pages\/31\/revisions\/"}],"predecessor-version":[{"id":1125,"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/pages\/31\/revisions\/1125\/"}],"wp:attachment":[{"href":"https:\/\/amtmusic.vn\/vi\/wp-json\/wp\/v2\/media\/?parent=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}